{"id":3086,"date":"2023-01-25T19:51:12","date_gmt":"2023-01-25T19:51:12","guid":{"rendered":"https:\/\/gallardodiesel.com\/producto\/reman-f2r-injector-a9360702187\/"},"modified":"2023-09-12T14:43:28","modified_gmt":"2023-09-12T14:43:28","slug":"reman-f2r-injector-a9360702187","status":"publish","type":"product","link":"https:\/\/gallardodiesel.com\/it\/producto\/reman-f2r-injector-a9360702187\/","title":{"rendered":"INIETTORE REMAN MERCEDES A9360702187"},"content":{"rendered":"<p>Iniettore A9360702187 completamente rigenerato per MERCEDES Euro 6<\/p>\n<p>In qualit\u00e0 di Centro Assistenza Ufficiale Delphi Diesel, disponiamo di un ampio stock di iniettori nei nostri magazzini in Spagna e Germania.<\/p>\n<p>I nostri prodotti sono forniti come mostrato nella foto:<\/p>\n<p>Riparato con ricambio originale Delphi.<br \/>\nIniettore imballato nella scatola originale Delphi.<br \/>\nProtocollo ufficiale di superamento dei test sui nostri banchi Hartridge CRI PRO.<\/p>\n<p>Il nuovo codice di correzione permette di ottimizzare le prestazioni dell&#8217;iniettore A9360702187 per MERCEDES.<\/p>\n<p>Effettuiamo spedizioni espresse in tutto il mondo, quindi potete chiederci una stima dei tempi di consegna.<\/p>\n<p>Tutti i nostri prodotti hanno una garanzia di due anni.<\/p>\n<p>Riferimenti incrociati:<\/p>\n<p>Mercedes &#8211; A9360702187<\/p>\n<p>Mercedes &#8211; A9362187<\/p>\n<p>Mercedes &#8211; A 936 070 21 87<\/p>\n<p>Delphi &#8211; BEBJ1C01001<\/p>\n<p>Delphi &#8211; BEBJ1C01002<\/p>\n<p>Delphi &#8211; HRE387<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniettore A9360702187 completamente rigenerato per MERCEDES Euro 6 In qualit\u00e0 di Centro Assistenza Ufficiale Delphi Diesel, disponiamo di un ampio stock di iniettori nei nostri magazzini in Spagna e Germania. I nostri prodotti sono forniti come mostrato nella foto: Riparato con ricambio originale Delphi. Iniettore imballato nella scatola originale Delphi. Protocollo ufficiale di superamento dei [&hellip;]<\/p>\n","protected":false},"featured_media":2832,"template":"","meta":[],"product_cat":[71,82],"product_tag":[],"class_list":["post-3086","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-delphi-it","product_cat-f2r-it"],"_links":{"self":[{"href":"https:\/\/gallardodiesel.com\/it\/wp-json\/wp\/v2\/product\/3086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gallardodiesel.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gallardodiesel.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gallardodiesel.com\/it\/wp-json\/wp\/v2\/media\/2832"}],"wp:attachment":[{"href":"https:\/\/gallardodiesel.com\/it\/wp-json\/wp\/v2\/media?parent=3086"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gallardodiesel.com\/it\/wp-json\/wp\/v2\/product_cat?post=3086"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gallardodiesel.com\/it\/wp-json\/wp\/v2\/product_tag?post=3086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}