{"id":3195,"date":"2023-01-25T19:46:48","date_gmt":"2023-01-25T19:46:48","guid":{"rendered":"https:\/\/gallardodiesel.com\/producto\/reman-f2p-injector-1974030\/"},"modified":"2023-09-12T15:51:35","modified_gmt":"2023-09-12T15:51:35","slug":"reman-f2p-injector-1974030","status":"publish","type":"product","link":"https:\/\/gallardodiesel.com\/fr\/producto\/reman-f2p-injector-1974030\/","title":{"rendered":"INJECTEUR DAF 1974030"},"content":{"rendered":"<p>Injecteur 1974030 enti\u00e8rement reconditionn\u00e9 pour DAF Euro 6<\/p>\n<p>En tant que Service Officiel Delphi Diesel Center, nous disposons d&#8217;un large stock d&#8217;injecteurs dans nos entrep\u00f4ts en Espagne et en Allemagne.<\/p>\n<p>Nos produits sont livr\u00e9s comme indiqu\u00e9 sur la photo :<\/p>\n<p>R\u00e9par\u00e9 avec une pi\u00e8ce de rechange Delphi d&#8217;origine.<br \/>\nInjecteur emball\u00e9 dans la bo\u00eete d&#8217;origine Delphi.<br \/>\nProtocole officiel de passage des tests sur nos bancs Hartridge CRI PRO.<\/p>\n<p>Le nouveau code de correction permet d&#8217;optimiser les performances de l&#8217;injecteur 1974030 pour DAF.<\/p>\n<p>Nous exp\u00e9dions en express dans le monde entier, vous pouvez donc nous demander une estimation du d\u00e9lai de livraison.<\/p>\n<p>Tous nos produits sont garantis deux ans.<\/p>\n<p>R\u00e9f\u00e9rences crois\u00e9es :<\/p>\n<p>&nbsp;<\/p>\n<p>DAF &#8211; 1974030<\/p>\n<p>DAF &#8211; 1974030R<\/p>\n<p>Delphi &#8211; BEBJ1D03001<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Injecteur 1974030 enti\u00e8rement reconditionn\u00e9 pour DAF Euro 6 En tant que Service Officiel Delphi Diesel Center, nous disposons d&#8217;un large stock d&#8217;injecteurs dans nos entrep\u00f4ts en Espagne et en Allemagne. Nos produits sont livr\u00e9s comme indiqu\u00e9 sur la photo : R\u00e9par\u00e9 avec une pi\u00e8ce de rechange Delphi d&#8217;origine. Injecteur emball\u00e9 dans la bo\u00eete d&#8217;origine Delphi. [&hellip;]<\/p>\n","protected":false},"featured_media":2822,"template":"","meta":[],"product_cat":[74,75],"product_tag":[],"class_list":["post-3195","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-delphi-fr","product_cat-f2p-fr"],"_links":{"self":[{"href":"https:\/\/gallardodiesel.com\/fr\/wp-json\/wp\/v2\/product\/3195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gallardodiesel.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gallardodiesel.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gallardodiesel.com\/fr\/wp-json\/wp\/v2\/media\/2822"}],"wp:attachment":[{"href":"https:\/\/gallardodiesel.com\/fr\/wp-json\/wp\/v2\/media?parent=3195"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gallardodiesel.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3195"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gallardodiesel.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}